{"id":1127,"date":"2018-06-11T12:25:46","date_gmt":"2018-06-11T12:25:46","guid":{"rendered":"https:\/\/live-english.net\/?p=1127"},"modified":"2018-06-11T12:25:46","modified_gmt":"2018-06-11T12:25:46","slug":"toeic-sprechtipps","status":"publish","type":"post","link":"https:\/\/live-english.net\/de\/toeic-sprechtipps\/","title":{"rendered":"TOEIC Sprechtipps"},"content":{"rendered":"<p>TOEIC-Mitarbeiten d\u00fcrfen weder Tipps noch Hinweise \u00fcber die TOEIC Pr\u00fcfung an die \u00d6ffentlichkeit geben, wenn sie es d\u00fcrften, dann w\u00fcrden sie ungef\u00e4hr folgendes sagen:<\/p>\n<h2>\u201cIch m\u00f6chte Sie verstehen k\u00f6nnen\u201d<\/h1>\n<p>Dies bedeutet, dass Sie klar und in einem angemessenen Tempo sprechen m\u00fcssen. Sie m\u00fcssen wissen, dass Sie schwer zu verstehen sind, wenn Sie zu schnell oder so langsam sprechen, dass Ihre Sprache keine Intonation hat. Auch dadurch erreichen Sie weniger Punkte. <\/p>\n<p>Hier kommen \u00dcbung und das Aufzeichnen Ihrer Stimme ins Spiel. H\u00f6ren Sie sich Ihre eigene Stimme an und seien Sie kritisch. Wenn Sie Ihre Stimme nicht mindestens einmal aufgenommen haben, dann haben Sie sich nicht gut genug vorbereitet.<\/p>\n<h2>\u201cIch m\u00f6chte Ihr bestes Englisch h\u00f6ren\u201d<\/h2>\n<p>Verwenden Sie keinen Slang. Gebrauchen Sie keine Umgangssprache oder unh\u00f6fliche Ausdr\u00fccke. Im Marketingmaterial finden Sie eine Spalte \u00fcber Intonation, Zeichensetzung, Grammatik, Vokabeln und Inhalt aber nicht f\u00fcr Coolness oder Witz. Reservieren Sie ihren Slang, um Ihre Freunde zu beeindrucken.<\/p>\n<h2>\u201cW\u00fcrzen Sie ein bisschen\u201d<\/h2>\n<p>Stellen Sie sich vor, Ihr Job besteht darin sich alle Aufnahmen anzuh\u00f6ren. Wenn alle Kandidaten mit langweiliger monotoner Stimme sprechen, dann ist das Ihre Chance mit nur etwas Intonation und Variation von Tonh\u00f6he und Lautst\u00e4rke herauszustechen. Versuchen Sie es, variieren Sie die Tonh\u00f6he, Lautst\u00e4rke und verwenden Sie Intonation in Ihrer Sprache, sodass Ihre Stimme sofort attraktiver klingt.<\/p>\n<h2>\u201cLangweilen Sie nicht!!\u201d<\/h2>\n<p>Vielen Sch\u00fclern wird beigebracht auf <em>how are you?<\/em> mit <em>I\u2018m fine<\/em> zu antworten. Ein wenig bekanntes Geheimnis: Wenn ein englischer Muttersprachler diese Reaktion zeigen w\u00fcrde, dann w\u00fcrde ich annehmen, dass er nicht mit mir sprechen m\u00f6chte. I w\u00fcrde denken, dass er mir die Standardantwort gegeben hat, weil er kein Interesse hat sich mit mir zu unterhalten.<\/p>\n<p>Standardworte sind platt. Sie sind ohne Geschmack. Worte wie <em>good und fine<\/em> und <em>OK<\/em> sollten Sie meiden, verwenden Sie hervorragend, fantastisch oder gehen Sie ins Detail. Ein guter Lehrer kann ein begnadeter Lehrer, ein guter Tag kann ein erinnernswerter Tag und eine gute Nachspeise kann \u00fcberw\u00e4ltigend sein.<\/p>\n<p>Die Bewerter m\u00f6chten die Vokabeln h\u00f6ren, die Sie kennen, vermeiden Sie daher gew\u00f6hnliche Worte, wenn Sie die Antworten f\u00fcr den TOEIC aufnehmen, \u00fcbertreiben Sie mit der doppelten Schokoladenfreude und dem Passionsfruchtstrudel.<\/p>\n<h2>\u201c\u00dcben Sie als ob Sie es ernst nehmen\u201d<\/h2>\n<p>Wenn Sie zu hause oder mit Ihrem <a href=\"https:\/\/live-english.net\/de\/virtuelle-sprachschule\/online-englischlehrer\/\" title=\"Englischlehrer\">Englischlehrer<\/a> \u00fcben, simulieren Sie reale Bedingungen, was bedeutet, dass Sie mit Ablenkungen und Hintergrundger\u00e4uschen \u00fcben sollten. Schalten Sie den Fernseher ein und schauen Sie in die andere Richtung, um dies zu erreichen. Machen Sie all die anderen oben genannten Sachen, wenn Sie \u00fcben. \u00dcben Sie nicht nur den Inhalt, sondern auch die Stimme, Geschwindigkeit, Intonation, Vokabeln etc.<\/p>\n <aside id=\"custom_html-66\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div>\r\n\t<br><br>\r\n<\/div>\r\n<!--EN-->\r\n <!--FR-->\r\n<!--IT-->\r\n<aside id=\"custom_html-77\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=de&amp;referred_by=CTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img alt=\"Book your free English trial lesson\" src='https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/CTA-probestunde.jpg'><\/a>\t\r\n<\/div><\/div><\/aside><!--DE-->\r\n <!--ES-->\r\n <!--HE-->\r\n <!--RU--><\/div><\/aside>","protected":false},"excerpt":{"rendered":"<p>TOEIC-Mitarbeiten d\u00fcrfen weder Tipps noch Hinweise \u00fcber die TOEIC Pr\u00fcfung an die \u00d6ffentlichkeit geben, wenn sie es d\u00fcrften, dann w\u00fcrden sie ungef\u00e4hr folgendes sagen: \u201cIch m\u00f6chte Sie verstehen k\u00f6nnen\u201d Dies bedeutet, dass Sie klar und in einem angemessenen Tempo sprechen<\/p>\n","protected":false},"author":1,"featured_media":34366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[29],"tags":[169,55],"class_list":["post-1127","post","type-post","status-publish","format-standard","hentry","category-englischpruefungen","tag-sprachen","tag-toeic"],"_links":{"self":[{"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/posts\/1127","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/comments?post=1127"}],"version-history":[{"count":0,"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/posts\/1127\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/media\/34366"}],"wp:attachment":[{"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/media?parent=1127"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/categories?post=1127"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-english.net\/de\/wp-json\/wp\/v2\/tags?post=1127"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}