{"id":1061,"date":"2018-06-11T08:37:37","date_gmt":"2018-06-11T08:37:37","guid":{"rendered":"https:\/\/live-english.net\/?p=1061"},"modified":"2023-12-21T11:47:18","modified_gmt":"2023-12-21T11:47:18","slug":"come-scrivere-carta-presentacion-inglese","status":"publish","type":"post","link":"https:\/\/live-english.net\/es\/come-scrivere-carta-presentacion-inglese\/","title":{"rendered":"Come scrivere una carta de presentaci\u00f3n in inglese"},"content":{"rendered":"<p>En estos tiempos, un curriculum vitae brillante lleno de experiencias de trabajo y t\u00edtulos no es ya suficiente. Es necesario ser capaz de resumir estos en una carta de presentaci\u00f3n que te venda como candidato o ning\u00fan reclutador se molestar\u00e1 en leer tu curriculum.<\/p>\n<h2>Escribir una carta de presentaci\u00f3n<\/h2>\n<p>Por lo tanto, \u00bfc\u00f3mo escribir una carta de presentaci\u00f3n que asegure que tu curriculum sea de los le\u00eddos? Mantenla simple, interesante e informativa.<br \/>\nPuedes utilizar el Asistente para cartas de presentaci\u00f3n que se encuentra en la mayor\u00eda de los procesadores de texto. A continuaci\u00f3n hablaremos de c\u00f3mo venderse.<br \/>\n<aside id=\"custom_html-81\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><!--EN-->\r\n <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n<aside id=\"custom_html-85\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=es&amp;referred_by=sCTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/sCTA-es.jpg\" alt=\"Book your Free English Trial lesson\" \/><\/a><\/div><\/aside> <!--ES-->\r\n <!--HE\r\n[do_widget id=custom_html-72] <!--RU-->\r\n<div>\r\n\t<br><br>\r\n<\/div><\/div><\/aside><\/p>\n<h2>Consejos para escribir una carta de presentaci\u00f3n en ingl\u00e9s<\/h2>\n<p>Lo m\u00e1s importante es no decirles lo bueno que eres, sino el gran trabajo que har\u00e1s para ellos. Com\u00e9ntales que si te contratan les har\u00e1s la vida m\u00e1s f\u00e1cil. \u00a1Confiad en m\u00ed!, \u00a1eso es lo que quieren o\u00edr! As\u00ed que en lugar de escribir tengo un t\u00edtulo en ingl\u00e9s, un master en Educaci\u00f3n y ocho a\u00f1os de experiencia, debes decirles que mi master en Educaci\u00f3n y mi experiencia me ayudan a conseguir la m\u00e1xima diversi\u00f3n e interactividad en las clases.<\/p>\n<p><strong>Se sincero.<\/strong> Esto significa que no debes decirles lo que piensas que quieren o\u00edr; d\u00edles porqu\u00e9 quieres el trabajo: I am applying for your company because I really like to help students and I think that the experience I will gain in your company will help me to reach my goal of being a great teacher.<\/p>\n<p><strong>Menciona los puntos negativos, pero sigue y remarca los positivos:<\/strong> I am available to start from December when I graduate as I would like to join your team as a qualified, skilled employee.<\/p>\n<p><strong>No utilice palabras negativas.<\/strong> En lugar de pedir perd\u00f3n por no responder m\u00e1s r\u00e1pido (sorry for not replying faster), agradece su paciencia (thank you for your patience), he estado bastante ocupado \u00faltimamente&#8230; (I have been quite busy lately\u2026) Este peque\u00f1o cambio hace que tu carta suene m\u00e1s positiva y alegre. Recuerdas que est\u00e1s dando una primera impresi\u00f3n por lo que el tono es important\u00edsimo.<\/p>\n<h2>Enviando tu carta de presentaci\u00f3n<\/h2>\n<p>Cuando env\u00edes tu carta de presentaci\u00f3n, c\u00f3piala y p\u00e9gala en el cuerpo del email, no como fichero adjunto. Y no mandes m\u00e1s ficheros adjuntos que los requeridos, sino har\u00e1s que el email sea bloqueado al considerarlo sospechoso los programas gestores de correo y de protecci\u00f3n antivirus. <\/p>\n<p><strong>Buena Suerte.\t<\/strong><\/p>\n<hr \/>\n<h2>Job interview Express<\/h2>\n<p><a href=\"https:\/\/live-english.net\/contact-us\/\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-21607\" src=\"https:\/\/live-english.net\/wp-content\/uploads\/2022\/06\/job-interview-express.jpg\" alt=\"Job Interview Express\" width=\"800\" height=\"600\" srcset=\"https:\/\/live-english.net\/wp-content\/uploads\/2022\/06\/job-interview-express.jpg 800w, https:\/\/live-english.net\/wp-content\/uploads\/2022\/06\/job-interview-express-300x225.jpg 300w, https:\/\/live-english.net\/wp-content\/uploads\/2022\/06\/job-interview-express-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/member.booknstart.com\/billing\/568\/EUR\/bsite\/en\/3\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-21612\" src=\"https:\/\/live-english.net\/wp-content\/uploads\/2022\/10\/Job-interview-1.png\" alt=\"Job Interview in English Express Preparation\" width=\"200\" height=\"100\" \/><\/a><\/p>\n<hr \/>\n <aside id=\"custom_html-66\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div>\r\n\t<br><br>\r\n<\/div>\r\n<!--EN-->\r\n <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n<aside id=\"custom_html-78\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=es&amp;referred_by=CTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img alt=\"Book your free English trial lesson\" src='https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/CTA-prueba.jpg'><\/a>\t\r\n<\/div><\/div><\/aside> <!--ES-->\r\n <!--HE-->\r\n <!--RU--><\/div><\/aside>","protected":false},"excerpt":{"rendered":"<p>En estos tiempos, un curriculum vitae brillante lleno de experiencias de trabajo y t\u00edtulos no es ya suficiente. Es necesario ser capaz de resumir estos en una carta de presentaci\u00f3n que te venda como candidato o ning\u00fan reclutador se molestar\u00e1<\/p>\n","protected":false},"author":1,"featured_media":34553,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[152,320,150],"class_list":["post-1061","post","type-post","status-publish","format-standard","hentry","category-entrevista-de-trabajo-ingles","tag-carta-de-presentacion","tag-cover-letter-2","tag-entrevista-de-trabajo"],"_links":{"self":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/posts\/1061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/comments?post=1061"}],"version-history":[{"count":3,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/posts\/1061\/revisions"}],"predecessor-version":[{"id":34562,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/posts\/1061\/revisions\/34562"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/media\/34553"}],"wp:attachment":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/media?parent=1061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/categories?post=1061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/tags?post=1061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}