{"id":1381,"date":"2018-06-13T12:24:47","date_gmt":"2018-06-13T12:24:47","guid":{"rendered":"https:\/\/live-english.net\/?p=1381"},"modified":"2018-09-01T20:25:01","modified_gmt":"2018-09-01T20:25:01","slug":"conversacion-en-ingles","status":"publish","type":"post","link":"https:\/\/live-english.net\/es\/conversacion-en-ingles\/","title":{"rendered":"Agregue una conversaci\u00f3n en ingl\u00e9s a su rutina diaria"},"content":{"rendered":"<p>\u00bfAlguna vez se ha sentido como un conejo viendo faros cuando alguien le pregunta algo en ingl\u00e9s?<br \/>\n\u00bfSe queda boquiabierto cuando se encuentra en un entorno de habla inglesa?<br \/>\nSi respondi\u00f3 afirmativamente a cualquiera de estas preguntas, puede significar que necesita comenzar a incorporar el ingl\u00e9s a sus conversaciones cotidianas.<br \/>\nLa mayor\u00eda de las personas estar\u00eda de acuerdo en que cuando estudia un idioma hay momentos en los que simplemente no se logra encontrar la palabra correcta para lo que se quiere decir.<br \/>\nNo parece importar cu\u00e1ntas horas pase revisando libros de gram\u00e1tica o cu\u00e1ntos ejercicios hace al d\u00eda, al momento de querer hablar, \u00a1no sale nada! \u00bfPero por qu\u00e9 pasa eso?<br \/>\nHablar es una habilidad que desarrollamos con el tiempo y esto puede hacer que algunos alumnos se sientan frustrados; al ver que no pueden expresarse tan r\u00e1pido o f\u00e1cilmente como en su propio idioma. Otros temen que los nativos hablantes se r\u00edan de ellos o no entiendan su pronunciaci\u00f3n.<br \/>\nEstos desaf\u00edos pueden afectar realmente el progreso y la confianza del alumno, y todos sabemos que, si no nos sentimos c\u00f3modos haciendo algo, es m\u00e1s probable que dejemos de hacerlo.<br \/>\nEn un mundo donde hablar ingl\u00e9s se est\u00e1 volviendo cada vez m\u00e1s esencial para la comunicaci\u00f3n internacional, es una buena idea tratar de mantener <a href=\"https:\/\/live-english.net\/es\/cursos-ingles-online\/clases-conversacionales-en-ingles\/\" title='conversaciones en ingl\u00e9s'>conversaciones en ingl\u00e9s<\/a> en nuestra rutina diaria.\u00a1Aqu\u00ed hay algunas sugerencias para que lo intente!<\/p>\n<ul>\n<li>\u00bfPor qu\u00e9 no pedir a algunos colegas en el trabajo que formen un grupo de habla inglesa? Cada vez que se vean en la fuente de agua o en la cafeter\u00eda, podr\u00edan intercambiar algunas palabras en ingl\u00e9s sobre c\u00f3mo va su d\u00eda o cu\u00e1les son sus planes para despu\u00e9s del trabajo, por ejemplo. \u00a1Nunca se sabe, incluso podr\u00edan invitarlo a venir!\n<\/li>\n<li>\u00bfQuiere saber un buen m\u00e9todo? \u00a1Un n\u00famero sorprendente de hablantes nativos de ingl\u00e9s podr\u00eda estar viviendo a la vuelta de su esquina, buscando la misma oportunidad para practicar su idioma natal! Busque un buen caf\u00e9 y discute temas de inter\u00e9s, la mitad en su idioma y la otra mitad en ingl\u00e9s, \u00a1es una gran manera de aumentar su vocabulario y conocer gente nueva!<\/li>\n<li>\u00bfQui\u00e9n dijo que las conversaciones no pod\u00edan ser en l\u00ednea? \u00bfQu\u00e9 le parece poner sus redes sociales en ingl\u00e9s o comentarlas en dicho idioma? Le sorprender\u00e1 la cantidad de personas que responder\u00e1n a esto en ingl\u00e9s tambi\u00e9n, abriendo muchas oportunidades para chatear e interactuar con otros.\n<\/li>\n<\/ul>\n<p>Decida lo que decida hacer, recuerde mantenerse relajado y disfrutarlo. S\u00e9a paciente consigo mismo y s\u00e9a realista con las escalas de tiempo. Llevar un diario de video de su progreso es una buena forma de ver cu\u00e1nto ha avanzado. Despu\u00e9s de unos meses, \u00a1le impresionar\u00e1 la cantidad de palabras nuevas que ha aprendido!<\/p>\n<p><strong>Posibles preguntas para hacerse <\/strong><br \/>\nHave you ever experienced a rabbit in headlights feeling when speaking English?<br \/>\nWhich of these suggestions do you prefer and why?<br \/>\nWhat other suggestions you could make?<\/p>\n<h2>Colaborador: Profesor Janine<br \/>\n<\/h2>\n<p>Janine es originaria de Yorkshire, es profesora calificada profesionalmente con m\u00e1s de 15 a\u00f1os de experiencia, ha ense\u00f1ado a estudiantes de todas las edades <a href=\"https:\/\/live-english.net\/es\/cursos-ingles-online\/clases-ingles-negocios\/\" title='ingl\u00e9s para negocios'>ingl\u00e9s para negocios<\/a> e ingl\u00e9s acad\u00e9mico. A Janine le gusta ayudar a los estudiantes a hablar m\u00e1s fluido y sentirse confiados sobre s\u00ed mismos al hablar ingl\u00e9s. Janine no es una persona que \u00abpermite que la hierba crezca bajo sus pies\u00bb, le gusta aprender cosas nuevas, idiomas, viajar y est\u00e1 muy orgullosa de sus ra\u00edces de Yorkshire.<\/p>\n <aside id=\"custom_html-66\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div>\r\n\t<br><br>\r\n<\/div>\r\n<!--EN-->\r\n <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n<aside id=\"custom_html-78\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=es&amp;referred_by=CTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img alt=\"Book your free English trial lesson\" src='https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/CTA-prueba.jpg'><\/a>\t\r\n<\/div><\/div><\/aside> <!--ES-->\r\n <!--HE-->\r\n <!--RU--><\/div><\/aside>","protected":false},"excerpt":{"rendered":"<p>\u00bfAlguna vez se ha sentido como un conejo viendo faros cuando alguien le pregunta algo en ingl\u00e9s? \u00bfSe queda boquiabierto cuando se encuentra en un entorno de habla inglesa? Si respondi\u00f3 afirmativamente a cualquiera de estas preguntas, puede significar que<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[51],"tags":[222,244],"class_list":["post-1381","post","type-post","status-publish","format-standard","hentry","category-consejos","tag-conversaciones","tag-rutina"],"_links":{"self":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/posts\/1381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/comments?post=1381"}],"version-history":[{"count":0,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/posts\/1381\/revisions"}],"wp:attachment":[{"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/media?parent=1381"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/categories?post=1381"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-english.net\/es\/wp-json\/wp\/v2\/tags?post=1381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}