{"id":1153,"date":"2018-06-11T15:24:49","date_gmt":"2018-06-11T15:24:49","guid":{"rendered":"https:\/\/live-english.net\/?p=1153"},"modified":"2018-06-11T15:24:49","modified_gmt":"2018-06-11T15:24:49","slug":"anglais-affaires-confiance-pratique","status":"publish","type":"post","link":"https:\/\/live-english.net\/fr\/anglais-affaires-confiance-pratique\/","title":{"rendered":"L&rsquo;anglais des affaires, une affaire de confiance en soi et de pratique"},"content":{"rendered":"<p>Beaucoup de professionnels font appel \u00e0 Live-English.net pour les aider \u00e0 \u00eatre op\u00e9rationnels en anglais. Diff\u00e9rents cas de figure se pr\u00e9sentent \u00e0 nous. Chaque apprenant est unique et une r\u00e9ponse individualis\u00e9e est n\u00e9cessaire. Un point commun est partag\u00e9s, tous veulent \u00eatre \u00e0 l&rsquo;aise lors de leur prise de parole en anglais et les <a href=\"https:\/\/live-english.net\/fr\/ecole-langues-en-ligne\/cours-anglais-telephone\/\" title=\"cours d'anglais par t\u00e9l\u00e9phone\">cours d&rsquo;anglais par t\u00e9l\u00e9phone<\/a> ou l&rsquo;<a href=\"https:\/\/live-english.net\/fr\/ecole-langues-en-ligne\/cours-anglais-skype\/\" title=\"anglais par Skype\">anglais par Skype<\/a> leur offrent cette occasion unique de b\u00e9n\u00e9ficier d&rsquo;une solution vraiment adapt\u00e9e \u00e0 leurs besoins.<\/p>\n<h2>Comment gagner en confiance<\/h2>\n<p>Tout le monde n&rsquo;a pas eu la chance d&rsquo;<a href=\"https:\/\/live-english.net\/fr\/cours-anglais-ligne\/cours-anglais-affaires\/\" title=\"apprendre l'anglais des affaires\">apprendre l&rsquo;anglais des affaires<\/a> \u00e0 un haut niveau. Ainsi, il y a des professionnels qui ont gravi les \u00e9chelons en laissant toujours de c\u00f4t\u00e9 la question de l&rsquo;anglais. Jusqu&rsquo;au jour o\u00f9 ils se rendent compte qu&rsquo;ils ne peuvent pas continuer ainsi. Leur progression est mise \u00e0 mal par leur lacunes en anglais, ils ne peuvent plus y \u00e9chapper. Il faut redonner \u00e0 ces personnes l&rsquo;envie d&rsquo;am\u00e9liorer son anglais et leur montrer qu&rsquo;elles aussi peuvent d\u00e9passer leurs limites.<br \/>\n<strong>La solution que nous pr\u00e9conisons: 2-3 cours r\u00e9guliers sur une p\u00e9riode de 6 mois \u00e0 1 an<br \/>\n<\/strong><\/p>\n<h2>Pratiquer pour ne pas oublier<\/h2>\n<p>L&rsquo;autre cas typique est celui du professionnel qui a un anglais tout \u00e0 fait correct mais qui ne l&rsquo;utilise pas ou peu. Il a peur que le manque de pratique ne soit fatal \u00e0 son anglais. Il s&rsquo;agit de toujours garder l&rsquo;anglais en \u00e9veil gr\u00e2ce \u00e0 des sujets de conversation g\u00e9n\u00e9rale et d&rsquo;anglais des affaires.<br \/>\n<strong>La solution: 1 cours par semaine r\u00e9guli\u00e8rement<br \/>\n<\/strong><\/p>\n<h2>Aller droit au but<\/h2>\n<p>Enfin, il y a ceux qui veulent \u00e0 la fois gagner en confiance et pratique pour un objectif court ou moyen terme. Par exemple, se pr\u00e9parer \u00e0 un meeting avec un client \u00e9tranger, acqu\u00e9rir les automatismes pour bien appr\u00e9hender un entretien d&#8217;embauche en anglais, \u00eatre capable de parler de son industrie ou de sa profession, etc.<br \/>\n<strong>La solution: autant de cours que n\u00e9cessaire sur quelques semaines pour ma\u00eetriser en anglais le sujet que l&rsquo;on souhaite approfondir.<\/strong><\/p>\n<p>La possibilit\u00e9 de se sentir \u00e0 l&rsquo;aise en anglais des affaires est donn\u00e9e \u00e0 tous, il faut juste s&rsquo;en donner les moyens. Consacrer 30 min de son temps \u00e0 un cours d&rsquo;anglais particulier fera toute la diff\u00e9rence. Les progr\u00e8s se font sentir au bout de 10 cours seulement.<\/p>\n <aside id=\"custom_html-66\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div>\r\n\t<br><br>\r\n<\/div>\r\n<!--EN-->\r\n<aside id=\"custom_html-74\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&amp;referred_by=CTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img alt=\"Book your free English trial lesson\" src='https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/CTA-cours-gratuit.jpg'><\/a>\t\r\n<\/div><\/div><\/aside> <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n <!--ES-->\r\n <!--HE-->\r\n <!--RU--><\/div><\/aside>","protected":false},"excerpt":{"rendered":"<p>Beaucoup de professionnels font appel \u00e0 Live-English.net pour les aider \u00e0 \u00eatre op\u00e9rationnels en anglais. Diff\u00e9rents cas de figure se pr\u00e9sentent \u00e0 nous. Chaque apprenant est unique et une r\u00e9ponse individualis\u00e9e est n\u00e9cessaire. Un point commun est partag\u00e9s, tous veulent<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[183,182],"class_list":["post-1153","post","type-post","status-publish","format-standard","hentry","category-anglais-affaires","tag-anglais-des-affaires","tag-confiance"],"_links":{"self":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/1153","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/comments?post=1153"}],"version-history":[{"count":0,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/1153\/revisions"}],"wp:attachment":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/media?parent=1153"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/categories?post=1153"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/tags?post=1153"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}