{"id":1173,"date":"2018-06-11T15:51:03","date_gmt":"2018-06-11T15:51:03","guid":{"rendered":"https:\/\/live-english.net\/?p=1173"},"modified":"2024-01-23T11:55:00","modified_gmt":"2024-01-23T11:55:00","slug":"reunions-affaires-anglais","status":"publish","type":"post","link":"https:\/\/live-english.net\/fr\/reunions-affaires-anglais\/","title":{"rendered":"Comment g\u00e9rer les r\u00e9unions d&rsquo;affaires en anglais quand l&rsquo;anglais n&rsquo;est pas votre langue maternelle"},"content":{"rendered":"<p>Les r\u00e9unions en anglais ne sont pas des situations rares pour les hommes d&rsquo;affaires. L&rsquo;anglais est en effet la langue des affaires par excellence et c&rsquo;est un inconv\u00e9nient non n\u00e9gligeable pour une entreprise qui veut tisser des liens \u00e0 l&rsquo;international si elle ne peut pas compter sur des employ\u00e9s et des cadres capable de <a href=\"https:\/\/live-english.net\/fr\/cours-anglais-ligne\/cours-conversation-anglais\/\" title=\"parler anglais couramment\">parler anglais couramment<\/a>. <\/p>\n<h2>Pourquoi les r\u00e9unions en anglais sont-elle si difficiles parfois?<\/h2>\n<p>Si vous avez d\u00e9j\u00e0 pris part \u00e0 des meetings en anglais, vous avez s\u00fbrement p\u00fb observer les difficult\u00e9s suivantes: <\/p>\n<ul>\n<li><strong>La langue parl\u00e9e dans les r\u00e9unions en anglais est bien diff\u00e9rente de l&rsquo;anglais de conversation.<\/strong> L&rsquo;anglais des affaires est davantage tourn\u00e9 vers des sujets li\u00e9s \u00e0 l&rsquo;entreprise et \u00e0 l&rsquo;\u00e9conomie. Dans beaucoup de meetings en anglais, vous pouvez entendre un jargon parfois difficile \u00e0 comprendre pour les non-initi\u00e9s. <\/li>\n<li><strong>L&rsquo;anglais parl\u00e9 en r\u00e9union est souvent plus soutenu.<\/strong> Etant donn\u00e9 que des sujets importants sont trait\u00e9s pendant ces r\u00e9unions et que les personnes r\u00e9unies sont souvent des coll\u00e8gues, des associ\u00e9s, des clients voire des concurrents, il est important de montrer des marques de respect entre les interlocuteurs.<\/li>\n<li><strong>Le temps est pr\u00e9cieux, et les hommes d&rsquo;affaires le savent plus que tout.<\/strong> Ainsi, les r\u00e9unions d&rsquo;affaires sont limit\u00e9es en temps, ce qui pousse certains \u00e0 parler plus rapidement pour pouvoir couvrir un plus grand nombre d&rsquo;id\u00e9es \u00e0 discuter. <\/li>\n<\/ul>\n<p>Il peut \u00eatre un d\u00e9fi de suivre tout ce qui se dit au cours de la r\u00e9union en anglais. Cependant, il existe des moyens de se pr\u00e9parer et de passer outre les difficult\u00e9s, de comprendre et d&rsquo;y participer comme il se doit. N\u00e9anmoins, seule une pratique r\u00e9guli\u00e8re vous permettra de ma\u00eetriser compl\u00e8tement ce genre de situation.<br \/>\n<aside id=\"custom_html-81\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><!--EN-->\r\n<aside id=\"custom_html-82\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&amp;referred_by=sCTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/sCTA-fr2.jpg\" alt=\"Book your Free English Trial lesson\" \/><\/a><\/div><\/aside> <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n <!--ES-->\r\n <!--HE\r\n[do_widget id=custom_html-72] <!--RU-->\r\n<div>\r\n\t<br><br>\r\n<\/div><\/div><\/aside><\/p>\n<h2>Nos conseils pour g\u00e9rer des r\u00e9unions d&rsquo;affaires en anglais<\/h2>\n<ul>\n<ol><strong>1. Etudiez le vocabulaire li\u00e9 \u00e0 votre industrie ou domaine d&rsquo;activit\u00e9.<\/strong> Il est essentiel de bien conna\u00eetre les termes li\u00e9s \u00e0 votre entreprise. Par exemple, si vous vendez des pi\u00e8ces d\u00e9tach\u00e9es de voitures et que vous avez un rendez-vous avec un client ou un fournisseur, il est important de conna\u00eetre des mots comme  \u201cengine\u201d, \u201cbrakes\u201d, \u201cvalves\u201d et \u201cpistons\u201d, car ils seront s\u00fbrement abord\u00e9s pendant la conversation. <\/ol>\n<ol><strong>2. Faites une liste de vos id\u00e9es principales.<\/strong> Ecrivez quelques id\u00e9es que vous souhaitez exprimer pendant votre r\u00e9union en anglais et pendez \u00e0 plusieurs fa\u00e7on de les dire. Soyez concis et pr\u00e9cis pour mieux vous en rappeler. <\/ol>\n<ol><strong>3. N&rsquo;h\u00e9sitez pas \u00e0 prendre avec-vous les notes que vous avez pr\u00e9par\u00e9es.<\/strong> Elles peuvent \u00eatre utiles lorsque ce sera votre tour de parler. Vous pouvez les consulter si vous avez oubli\u00e9 un mot ou une information importante. <\/ol>\n<\/ul>\n<p>Vous pouvez vous entra\u00eener en regardant quelques vid\u00e9os de r\u00e9unions en anglais sur Youtube. En les \u00e9coutant avec attention et en r\u00e9p\u00e9tant certaines expressions, vous vous sentirez plus \u00e0 l&rsquo;aise pour vos propres meetings.<\/p>\n<p>N&rsquo;abandonnez pas, avec le temps, vous pourrez affiner vos comp\u00e9tences et g\u00e9rer au mieux ces situations parfois stressantes de r\u00e9unions en anglais.<\/p>\n<p>Si vous souhaitez am\u00e9liorer votre anglais des affaires, \u00e9tendre votre vocabulaire, et savoir mieux utiliser des expressions de la vie de tous les jours, vous pourrez prendre des <a href=\"https:\/\/live-english.net\/fr\/cours-anglais-ligne\/cours-anglais-affaires\/\" title=\"cours d&#039;anglais des affaires en ligne\">cours d&rsquo;anglais des affaires en ligne<\/a>. Vous pourrez vous concentrer sur ce qui vous int\u00e9resse sp\u00e9cifiquement avec votre professeur particulier en ligne. Nos cours de 30 min sont facile \u00e0 caser m\u00eame si vous avez un emploi du temps charg\u00e9.<\/p>\n <aside id=\"custom_html-66\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div>\r\n\t<br><br>\r\n<\/div>\r\n<!--EN-->\r\n<aside id=\"custom_html-74\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&amp;referred_by=CTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img alt=\"Book your free English trial lesson\" src='https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/CTA-cours-gratuit.jpg'><\/a>\t\r\n<\/div><\/div><\/aside> <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n <!--ES-->\r\n <!--HE-->\r\n <!--RU--><\/div><\/aside>","protected":false},"excerpt":{"rendered":"<p>Les r\u00e9unions en anglais ne sont pas des situations rares pour les hommes d&rsquo;affaires. L&rsquo;anglais est en effet la langue des affaires par excellence et c&rsquo;est un inconv\u00e9nient non n\u00e9gligeable pour une entreprise qui veut tisser des liens \u00e0 l&rsquo;international<\/p>\n","protected":false},"author":1,"featured_media":36249,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31],"tags":[190],"class_list":["post-1173","post","type-post","status-publish","format-standard","hentry","category-anglais-affaires","tag-reunion"],"_links":{"self":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/1173","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/comments?post=1173"}],"version-history":[{"count":1,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/1173\/revisions"}],"predecessor-version":[{"id":36257,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/1173\/revisions\/36257"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/media\/36249"}],"wp:attachment":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/media?parent=1173"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/categories?post=1173"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/tags?post=1173"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}