{"id":24766,"date":"2023-02-24T12:47:59","date_gmt":"2023-02-24T12:47:59","guid":{"rendered":"https:\/\/live-english.net\/?p=24766"},"modified":"2023-02-24T12:49:57","modified_gmt":"2023-02-24T12:49:57","slug":"introduction-aux-idiomes-en-anglais","status":"publish","type":"post","link":"https:\/\/live-english.net\/fr\/introduction-aux-idiomes-en-anglais\/","title":{"rendered":"Introduction aux idiomes en anglais"},"content":{"rendered":"<p>Avez-vous remarqu\u00e9 qu&rsquo;en anglais (et m\u00eame dans d&rsquo;autres langues) ce qu&rsquo;on dit n&rsquo;a pas toujours un sens litt\u00e9ral. Parfois, lorsqu&rsquo;on met deux mots \u00e0 la suite, cela cr\u00e9e un nouveau sens. Par exemple: <em>Every morning I <strong>get up<\/strong> at 7 o\u2019clock.<\/em> Que signifie <strong>get up<\/strong>? On sait bien que <strong>get<\/strong> veut dire recevoir, et que <strong>up<\/strong> veut dire en haut. Mais <strong>get up<\/strong> ne veut pas dire recevoir en haut, n&rsquo;est-ce pas?<\/p>\n<h2>Qu&rsquo;est-ce qu&rsquo;un idiome en anglais?<\/h2>\n<p>Lorsque vous assemblez des mots pour cr\u00e9er un sens diff\u00e9rent du sens des mots individuels, vous cr\u00e9ez ce que nous appelons une expression idiomatique ou un idiome. Les idiomes viennent de la langue parl\u00e9e et ils sont essentiellement un nouveau vocabulaire que nous cr\u00e9ons en utilisant l&rsquo;ancien vocabulaire parce que nous sommes trop paresseux ou sans imagination pour penser \u00e0 de nouveaux mots. Ou peut-\u00eatre parce qu&rsquo;en utilisant des mots qui existent d\u00e9j\u00e0, nous pouvons donner un indice sur le sens.<br \/>\n<aside id=\"custom_html-81\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><!--EN-->\r\n<aside id=\"custom_html-82\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&amp;referred_by=sCTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/sCTA-fr2.jpg\" alt=\"Book your Free English Trial lesson\" \/><\/a><\/div><\/aside> <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n <!--ES-->\r\n <!--HE\r\n[do_widget id=custom_html-72] <!--RU-->\r\n<div>\r\n\t<br><br>\r\n<\/div><\/div><\/aside><br \/>\nCertains idiomes sont faciles \u00e0 deviner \u00e0 cause des mots qui les composent. Par exemple, <strong>get up<\/strong> (se lever), <strong>look around <\/strong>(regarder autour de soi), <strong>eat out<\/strong> (aller au restaurant). Mais m\u00e9fiez-vous. Ils peuvent avoir une signification cach\u00e9e que vous ne pouvez pas deviner. <strong>Eating out<\/strong> veut bien dire sortir (au restaurant) et manger mais cela ne veut pas die que vous mangez \u00e0 la belle \u00e9toile. Si vous voulez dire que vous mangez dehors, par exemple, dans votre jardin, il faut dire <strong>eating outside<\/strong> et non <strong>eating out<\/strong>.<\/p>\n<p>Le sens d&rsquo;autres idiomes peut \u00eatre plus difficile \u00e0 deviner. Par exemple, <strong>work out<\/strong> (faire de l&rsquo;exercice), <strong>kick the bucket<\/strong> (mourir), <strong>give up<\/strong> (abandonner).<\/p>\n<h2>Pourquoi utiliser les idiomes en anglais?<\/h2>\n<p>Les idiomes sont souvent intraduisible litt\u00e9ralement car ils ne marchent que dans une langue. Essayez! Traduisez <em>kick<\/em>, <em>the <\/em>and <em>bucket<\/em> en fran\u00e7ais. Est-ce que cela ressemble \u00e0 <em>mourir<\/em>? Pas vraiment.<\/p>\n<p>L&rsquo;apprentissage des expressions idiomatiques est important lors de l&rsquo;apprentissage de l&rsquo;anglais, car elles constituent un moyen courant et naturel pour les anglophones de communiquer. C&rsquo;est \u00e9galement utile pour vous aider \u00e0 avoir l&rsquo;air de parler plus couramment et naturellement lorsque vous parlez ou \u00e9crivez en anglais. Les utiliser correctement peut \u00e9galement vous aider \u00e0 transmettre votre message plus efficacement, en utilisant les expressions utilis\u00e9es dans la vie de tous les jours.<\/p>\n<p>En plus, les expressions idiomatiques sont souvent utilis\u00e9es dans des contextes informels tels que des conversations avec des amis, et elles peuvent vous aider \u00e0 vous connecter avec des anglophones et \u00e0 mieux comprendre la culture.<br \/>\nL&rsquo;apprentissage des expressions idiomatiques est donc un aspect essentiel de la ma\u00eetrise et de la ma\u00eetrise de la langue anglaise.<\/p>\n<p>Les idiomes sont amusants \u00e0 apprendre et ils rendent la langue beaucoup plus color\u00e9e, donc si vous souhaitez en savoir plus, je vous recommande de prendre un bon dictionnaire pour les expressions idiomatiques ou de googler chaque fois que vous entendez une combinaison de mots qui semble n&rsquo;avoir aucun sens. Enjoy.<\/p>\n <aside id=\"custom_html-66\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div>\r\n\t<br><br>\r\n<\/div>\r\n<!--EN-->\r\n<aside id=\"custom_html-74\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=fr&amp;referred_by=CTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img alt=\"Book your free English trial lesson\" src='https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/CTA-cours-gratuit.jpg'><\/a>\t\r\n<\/div><\/div><\/aside> <!--FR-->\r\n<!--IT-->\r\n<!--DE-->\r\n <!--ES-->\r\n <!--HE-->\r\n <!--RU--><\/div><\/aside>","protected":false},"excerpt":{"rendered":"<p>Avez-vous remarqu\u00e9 qu&rsquo;en anglais (et m\u00eame dans d&rsquo;autres langues) ce qu&rsquo;on dit n&rsquo;a pas toujours un sens litt\u00e9ral. Parfois, lorsqu&rsquo;on met deux mots \u00e0 la suite, cela cr\u00e9e un nouveau sens. Par exemple: Every morning I get up at 7<\/p>\n","protected":false},"author":1,"featured_media":24769,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[33],"tags":[],"class_list":["post-24766","post","type-post","status-publish","format-standard","hentry","category-ameliorer-anglais"],"_links":{"self":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/24766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/comments?post=24766"}],"version-history":[{"count":4,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/24766\/revisions"}],"predecessor-version":[{"id":24778,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/posts\/24766\/revisions\/24778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/media\/24769"}],"wp:attachment":[{"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/media?parent=24766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/categories?post=24766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-english.net\/fr\/wp-json\/wp\/v2\/tags?post=24766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}