{"id":1272,"date":"2018-06-12T19:13:05","date_gmt":"2018-06-12T19:13:05","guid":{"rendered":"https:\/\/live-english.net\/?p=1272"},"modified":"2023-05-06T16:32:56","modified_gmt":"2023-05-06T16:32:56","slug":"conversazioni-inglese-commerciale","status":"publish","type":"post","link":"https:\/\/live-english.net\/it\/conversazioni-inglese-commerciale\/","title":{"rendered":"Dieci cose che devi sapere sulle conversazioni in inglese commerciale"},"content":{"rendered":"<h2>1: l\u2019inglese commerciale \u00e8 diverso dall\u2019inglese colloquiale?<\/h2>\n<p>S\u00ec e no! Cosa significa? Nel mondo del lavoro la capacit\u00e0 di <a href=\"https:\/\/live-english.net\/it\/corsi-inglese-online\/corsi-conversazione-inglese\/\" title=\"conversare in inglese\">conversare in inglese<\/a> \u00e8 un requisito. Parlare del pi\u00f9 e del meno \u00e8 essenziale per costruire rapporti interpersonali con i vostri clienti.<\/p>\n<h3>Argomenti di cui parlare<\/h3>\n<p>Esempi di argomenti \u201crompighiaccio\u201d o \u201cfutili\u201d sono le conversazioni sul tempo atmosferico, notizie, traffico, voli aerei, famiglia e sport. Una regola vecchia e al contempo attuale consiglia di non rischiare di offendere l\u2019interlocutore parlando di politica, religione e sesso. Al giorno d\u2019oggi probabilmente a questa lista si possono aggiungere altri argomenti visto che siamo sempre pi\u00f9 sensibili a punti di vista differenti dal nostro.<br \/>\n<aside id=\"custom_html-81\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><!--EN-->\r\n <!--FR-->\r\n<aside id=\"custom_html-83\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=it&amp;referred_by=sCTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/sCTA-it.jpg\" alt=\"Book your Free English Trial lesson\" \/><\/a><\/div><\/aside><!--IT-->\r\n<!--DE-->\r\n <!--ES-->\r\n <!--HE\r\n[do_widget id=custom_html-72] <!--RU-->\r\n<div>\r\n\t<br><br>\r\n<\/div><\/div><\/aside><\/p>\n<h3>Prepara ci\u00f2 che vorrai dire<\/h3>\n<p>Prima, durante le pause e dopo una riunione \u00e8 il momento in cui colloquiare, mentre durante il meeting occorre essere professionali. Se stai esponendo le tue idee, probabilmente ti sei scritto precisamente cosa dire, e come gestire le obiezioni, ad esempio hai impostato il tutto per far capire il messaggio che vuoi lanciare. Anche conversazioni rompighiaccio possono essere impostate precedentemente.<\/p>\n<p>Pensiamo sia una buona idea prepararsi piccole e breve conversazioni in modo che risultino comunque improvvisate all\u2019interlocutore, e che non abbiano il tono professionale richiesto durante l\u2019orario lavorativo. Nelle conversazioni in inglese spicciolo sono presenti molti percorsi casuali, cosa che nell\u2019inglese commerciale si cerca di evitare andando dritti al punto del progetto o dell\u2019idea che si vuole esporre.<\/p>\n<p>Quindi, hai bisogno di specifiche <a href=\"https:\/\/live-english.net\/it\/corsi-inglese-online\/inglese-professionale-commerciale-online\/\" title=\"lezioni di inglese commerciali\">lezioni di inglese commerciali<\/a>? La risposta (che certo intuisci) tra poco&#8230;<\/p>\n <aside id=\"custom_html-66\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div>\r\n\t<br><br>\r\n<\/div>\r\n<!--EN-->\r\n <!--FR-->\r\n<aside id=\"custom_html-76\" class=\"widget_text widget widget_custom_html amr_widget\"><div class=\"textwidget custom-html-widget\"><div><a href=\"https:\/\/member.booknstart.com\/trial-registration?lg=it&amp;referred_by=CTA&amp;office_id=3\" title=\"Book a Free Trial Lesson\" target=\"_blank\" rel=\"noopener\"><img alt=\"Book your free English trial lesson\" src='https:\/\/live-english.net\/wp-content\/uploads\/2023\/02\/CTA-prova.jpg'><\/a>\t\r\n<\/div><\/div><\/aside><!--IT-->\r\n<!--DE-->\r\n <!--ES-->\r\n <!--HE-->\r\n <!--RU--><\/div><\/aside>","protected":false},"excerpt":{"rendered":"<p>1: l\u2019inglese commerciale \u00e8 diverso dall\u2019inglese colloquiale? S\u00ec e no! Cosa significa? Nel mondo del lavoro la capacit\u00e0 di conversare in inglese \u00e8 un requisito. Parlare del pi\u00f9 e del meno \u00e8 essenziale per costruire rapporti interpersonali con i vostri<\/p>\n","protected":false},"author":1,"featured_media":26538,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[48],"tags":[218],"class_list":["post-1272","post","type-post","status-publish","format-standard","hentry","category-inglese-commerciale","tag-conversazioni"],"_links":{"self":[{"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/posts\/1272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/comments?post=1272"}],"version-history":[{"count":1,"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/posts\/1272\/revisions"}],"predecessor-version":[{"id":26546,"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/posts\/1272\/revisions\/26546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/media\/26538"}],"wp:attachment":[{"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/media?parent=1272"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/categories?post=1272"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/live-english.net\/it\/wp-json\/wp\/v2\/tags?post=1272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}